{"id":239,"date":"2025-06-29T15:46:07","date_gmt":"2025-06-29T13:46:07","guid":{"rendered":"https:\/\/www.holaindiachiclana.com\/reserva-ahora\/"},"modified":"2026-06-21T15:09:06","modified_gmt":"2026-06-21T13:09:06","slug":"reserva-ahora","status":"publish","type":"page","link":"https:\/\/www.holaindiachiclana.com\/es\/reserva-ahora\/","title":{"rendered":"Reserva ahora"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbscallops\u00bb background_pattern_color=\u00bbgcid-fa957022-7f68-4c63-9382-2437a00591d9&#8243; background_pattern_vertical_offset=\u00bb-64px\u00bb background_pattern_repeat=\u00bbrepeat-x\u00bb custom_padding=\u00bb120px||||false|false\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-fa957022-7f68-4c63-9382-2437a00591d9%22:%91%22background_pattern_color%22%93}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb_initial\u00bb header_font=\u00bbBentham||||||||\u00bb header_text_color=\u00bb#E09900&#8243; header_font_size=\u00bb72px\u00bb header_letter_spacing=\u00bb-0.05em\u00bb header_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Reserva ahora<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb_initial\u00bb text_font=\u00bbInter||||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb header_font_size_tablet=\u00bb55px\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si tienes alguna alergia o necesidad alimentaria especial, o si est\u00e1s organizando un evento especial o una reserva de grupo, por favor, d\u00e9janos un mensaje. \u00a1Nuestro equipo se pondr\u00e1 en contacto contigo lo antes posible para asegurarse de que todo salga a la perfecci\u00f3n! <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_contact_form email=\u00bbreservas@holaindiachiclana.com\u00bb custom_message=\u00bbNew Booking Hola India||et_pb_line_break_holder||&#8211;||et_pb_line_break_holder||||et_pb_line_break_holder||Name: %%Name%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Phone: %%Phone%%||et_pb_line_break_holder||Date: %%Date%%||et_pb_line_break_holder||Time: %%Time%%||et_pb_line_break_holder||How Many: %%How_Many%%||et_pb_line_break_holder||Message: %%Message%%\u00bb success_message=\u00bbConfirmaremos tu reserva en breve. \u00a1Comprueba tu carpeta de correo no deseado! \u00bb submit_button_text=\u00bbENVIAR\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb_initial\u00bb _unique_id=\u00bb38951f8d-8be3-4d8b-b12d-124369dc5fa7&#8243; form_field_background_color=\u00bbRGBA(255,255,255,0)\u00bb form_field_text_color=\u00bb#000000&#8243; form_field_custom_padding=\u00bb16px|20px|16px|20px|true|true\u00bb form_field_font=\u00bbInter||||||||\u00bb form_field_font_size=\u00bb16px\u00bb form_field_line_height=\u00bb1.8em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0.2em\u00bb button_font=\u00bbInter|600||on|||||\u00bb button_custom_padding=\u00bb16px|24px|16px|24px|true|true\u00bb form_field_font_size_tablet=\u00bb15px\u00bb form_field_font_size_phone=\u00bb14px\u00bb form_field_font_size_last_edited=\u00bbon|tablet\u00bb border_color_all=\u00bb#000000&#8243; border_width_bottom=\u00bb1px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22button_bg_color%22%93}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNombre\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbEmail\u00bb field_type=\u00bbemail\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbPhone\u00bb field_title=\u00bbTel\u00e9fono\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbDate\u00bb field_title=\u00bbFecha\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbTime\u00bb field_title=\u00bbA que hora?\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbHow_Many\u00bb field_title=\u00bb\u00bfCu\u00e1ntos personas?\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb required_mark=\u00bboff\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbContact Info &#038; Map\u00bb _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d51402.05556337241!2d-6.255350051367208!3d36.36977710000001!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd0c333272c6590d%3A0x7b370d3670c19bee!2sHola%20Indian%20Restaurant!5e0!3m2!1sen!2ses!4v1751204702139!5m2!1sen!2ses\" width=\"400\" height=\"300\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bb856 508 578 &#8211; 613 254 465&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb36px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bb_initial\u00bb header_font=\u00bbInter||||||||\u00bb header_text_color=\u00bb#000000&#8243; header_font_size=\u00bb30px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bbInter||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb||10px||false|false\u00bb animation=\u00bboff\u00bb header_font_size_tablet=\u00bb32px\u00bb header_font_size_phone=\u00bb20px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb body_font_size_tablet=\u00bb15px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22icon_color%22%93}\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbreservas@holaindiachiclana.com\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf0e0;||fa||900&#8243; icon_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb36px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bb_initial\u00bb header_font=\u00bbInter||||||||\u00bb header_font_size=\u00bb30px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bbInter||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb||10px||false|false\u00bb animation=\u00bboff\u00bb hover_enabled=\u00bb0&#8243; header_font_size_tablet=\u00bb32px\u00bb header_font_size_phone=\u00bb20px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb body_font_size_tablet=\u00bb15px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22icon_color%22,%22icon_color%22%93}\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe081;||divi||400&#8243; icon_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb36px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bb_initial\u00bb header_font=\u00bbInter||||||||\u00bb header_text_color=\u00bb#000000&#8243; header_font_size=\u00bb37px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bbInter||||||||\u00bb body_text_color=\u00bb#000000&#8243; body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb||10px||false|false\u00bb animation=\u00bboff\u00bb header_font_size_tablet=\u00bb32px\u00bb header_font_size_phone=\u00bb20px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb body_font_size_tablet=\u00bb15px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22icon_color%22,%22icon_color%22%93}\u00bb text_font_size_tablet=\u00bb15px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb]<\/p>\n<p>Calle de la Boca, 4<br \/>Centro Comercial H\u00e9rcules, Local 27<br \/>11139 Chiclana de la Frontera, C\u00e1diz<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbgcid-fa957022-7f68-4c63-9382-2437a00591d9&#8243; background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbscallops\u00bb background_pattern_color=\u00bbrgba(187,156,109,0.2)\u00bb background_pattern_repeat_origin=\u00bbbottom_left\u00bb background_pattern_repeat=\u00bbrepeat-x\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_module=\u00bb103&#8243; saved_tabs=\u00bball\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-fa957022-7f68-4c63-9382-2437a00591d9%22:%91%22background_color%22%93}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; custom_padding_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; custom_padding=\u00bb60px|60px|60px|60px|true|true\u00bb custom_padding_tablet=\u00bb30px|30px|30px|30px|true|true\u00bb custom_padding_phone=\u00bb20px|20px|20px|20px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.holaindiachiclana.com\/wp-content\/uploads\/2025\/06\/hola-indian.jpg\u00bb alt=\u00bbRestaurante Indio Chiclana\u00bb title_text=\u00bbRestaurante Indio Chiclana\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb07bb8ad-68d5-46ab-9b7c-e949fe9df597&#8243; text_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb]Cena en casa o pide comida para llevar: te esperan sabor, tradici\u00f3n y calidez. \u00a1Esperamos recibirte pronto![\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bb660cb5ee-4581-4904-a2f2-0b63b7010739&#8243; header_4_text_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22header_4_text_color%22%93}\u00bb]<\/p>\n<h4>Horas<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbb07bb8ad-68d5-46ab-9b7c-e949fe9df597&#8243; text_text_color=\u00bbgcid-fa957022-7f68-4c63-9382-2437a00591d9&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{%22gcid-fa957022-7f68-4c63-9382-2437a00591d9%22:%91%22text_text_color%22%93}\u00bb]<\/p>\n<p><span style=\"color: #ffffff;\">Lunes-Domingo<\/span><br \/><span style=\"color: #ffffff;\">12:30 PM &#8211; 4:30 PM<\/span><br \/><span style=\"color: #ffffff;\">7:00 PM &#8211; 00:00 AM<\/span><br \/><span style=\"color: #ffffff;\">Martes 7:00 PM &#8211; 00:00 AM<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bb660cb5ee-4581-4904-a2f2-0b63b7010739&#8243; header_4_text_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb custom_margin=\u00bb40px||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22header_4_text_color%22%93}\u00bb]<\/p>\n<h4>Direcci\u00f3n<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbb07bb8ad-68d5-46ab-9b7c-e949fe9df597&#8243; text_text_color=\u00bbgcid-fa957022-7f68-4c63-9382-2437a00591d9&#8243; custom_margin=\u00bb||10px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-fa957022-7f68-4c63-9382-2437a00591d9%22:%91%22text_text_color%22%93}\u00bb]<\/p>\n<p><span style=\"color: #ffffff;\">Calle de la Boca, 4<\/span><br \/><span style=\"color: #ffffff;\">Centro Comercial H\u00e9rcules, Local 27<\/span><br \/><span style=\"color: #ffffff;\">11139 Chiclana de la Frontera, C\u00e1diz<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bb660cb5ee-4581-4904-a2f2-0b63b7010739&#8243; header_4_text_color=\u00bbgcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f\u00bb custom_margin=\u00bb||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-5b291cc9-df1d-4b6e-9bdc-386dacc5279f%22:%91%22header_4_text_color%22%93}\u00bb]<\/p>\n<h4>Horas<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbb07bb8ad-68d5-46ab-9b7c-e949fe9df597&#8243; text_text_color=\u00bbgcid-fa957022-7f68-4c63-9382-2437a00591d9&#8243; custom_margin=\u00bb||10px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-fa957022-7f68-4c63-9382-2437a00591d9%22:%91%22text_text_color%22%93}\u00bb]<span style=\"color: #ffffff;\">+34 856 508 578<\/span><br \/><span style=\"color: #ffffff;\">+34 613 254 465<\/span>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/www.holaindiachiclana.com\/es\/menu\/\u00bb button_text=\u00bbMen\u00fa\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbb364fbfc-2000-436d-ab45-52de35ab9496&#8243; custom_margin=\u00bb28px||28px||true|false\u00bb custom_padding=\u00bb16px|26px|16px|26px|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow icon_color=\u00bb#EDF000&#8243; use_icon_font_size=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbgcid-68c6b9ad-55a2-4756-9f20-a801af585cf6&#8243; background_enable_color=\u00bbon\u00bb custom_padding=\u00bb4px|4px|4px|4px|true|true\u00bb global_colors_info=\u00bb{%22gcid-68c6b9ad-55a2-4756-9f20-a801af585cf6%22:%91%22background_color%22%93}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbgcid-68c6b9ad-55a2-4756-9f20-a801af585cf6&#8243; background_enable_color=\u00bbon\u00bb custom_padding=\u00bb4px|4px|4px|4px|true|true\u00bb global_colors_info=\u00bb{%22gcid-68c6b9ad-55a2-4756-9f20-a801af585cf6%22:%91%22background_color%22,%22background_color%22%93}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reserva ahoraSi tienes alguna alergia o necesidad alimentaria especial, o si est\u00e1s organizando un evento especial o una reserva de grupo, por favor, d\u00e9janos un mensaje. \u00a1Nuestro equipo se pondr\u00e1 en contacto contigo lo antes posible para asegurarse de que todo salga a la perfecci\u00f3n! Calle de la Boca, 4Centro Comercial H\u00e9rcules, Local 2711139 Chiclana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-239","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/pages\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":16,"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/pages\/239\/revisions"}],"predecessor-version":[{"id":437,"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/pages\/239\/revisions\/437"}],"wp:attachment":[{"href":"https:\/\/www.holaindiachiclana.com\/es\/wp-json\/wp\/v2\/media?parent=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}